{"id":741,"date":"2019-04-18T16:15:28","date_gmt":"2019-04-18T14:15:28","guid":{"rendered":"http:\/\/www.herzensraum-coaching.at\/?p=741"},"modified":"2019-04-18T16:15:35","modified_gmt":"2019-04-18T14:15:35","slug":"warum-ich-es-liebe-coach-zu-sein","status":"publish","type":"post","link":"https:\/\/www.herzensraum-coaching.at\/en\/warum-ich-es-liebe-coach-zu-sein\/","title":{"rendered":"Warum ich es liebe, Coach zu sein!"},"content":{"rendered":"<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" data-attachment-id=\"743\" data-permalink=\"https:\/\/www.herzensraum-coaching.at\/en\/warum-ich-es-liebe-coach-zu-sein\/warum-coach\/\" data-orig-file=\"https:\/\/www.herzensraum-coaching.at\/wp-content\/uploads\/2019\/04\/Warum-Coach.jpg\" data-orig-size=\"1280,720\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Warum Coach\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.herzensraum-coaching.at\/wp-content\/uploads\/2019\/04\/Warum-Coach-1024x576.jpg\" src=\"https:\/\/www.herzensraum-coaching.at\/wp-content\/uploads\/2019\/04\/Warum-Coach-1024x576.jpg\" alt=\"\" class=\"wp-image-743\" srcset=\"https:\/\/www.herzensraum-coaching.at\/wp-content\/uploads\/2019\/04\/Warum-Coach-1024x576.jpg 1024w, https:\/\/www.herzensraum-coaching.at\/wp-content\/uploads\/2019\/04\/Warum-Coach-300x169.jpg 300w, https:\/\/www.herzensraum-coaching.at\/wp-content\/uploads\/2019\/04\/Warum-Coach-768x432.jpg 768w, https:\/\/www.herzensraum-coaching.at\/wp-content\/uploads\/2019\/04\/Warum-Coach.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Warum ich es liebe, Coach zu sein!<\/h2>","protected":false},"excerpt":{"rendered":"<p>Warum ich es liebe, Coach zu sein!<\/p>","protected":false},"author":2,"featured_media":747,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[94,11,225,226],"class_list":["post-741","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","tag-coach","tag-coaching","tag-erfolgreich","tag-traumberuf"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Warum ich es liebe, Coach zu sein! - Herzensraum-Coaching<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.herzensraum-coaching.at\/en\/warum-ich-es-liebe-coach-zu-sein\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Warum ich es liebe, Coach zu sein! - Herzensraum-Coaching\" \/>\n<meta property=\"og:description\" content=\"Warum ich es liebe, Coach zu sein!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.herzensraum-coaching.at\/en\/warum-ich-es-liebe-coach-zu-sein\/\" \/>\n<meta property=\"og:site_name\" content=\"Herzensraum-Coaching\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/herzensraum.coaching\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-18T14:15:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-18T14:15:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.herzensraum-coaching.at\/wp-content\/uploads\/2019\/04\/sunrise-1157963_1280.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nicole Riederer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nicole Riederer\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.herzensraum-coaching.at\\\/warum-ich-es-liebe-coach-zu-sein\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.herzensraum-coaching.at\\\/warum-ich-es-liebe-coach-zu-sein\\\/\"},\"author\":{\"name\":\"Nicole Riederer\",\"@id\":\"https:\\\/\\\/www.herzensraum-coaching.at\\\/#\\\/schema\\\/person\\\/551800e2d7057ae8b86ec5c758987b6f\"},\"headline\":\"Warum ich es liebe, Coach zu sein!\",\"datePublished\":\"2019-04-18T14:15:28+00:00\",\"dateModified\":\"2019-04-18T14:15:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.herzensraum-coaching.at\\\/warum-ich-es-liebe-coach-zu-sein\\\/\"},\"wordCount\":14,\"commentCount\":2,\"image\":{\"@id\":\"https:\\\/\\\/www.herzensraum-coaching.at\\\/warum-ich-es-liebe-coach-zu-sein\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.herzensraum-coaching.at\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/sunrise-1157963_1280.jpg\",\"keywords\":[\"Coach\",\"Coaching\",\"erfolgreich\",\"Traumberuf\"],\"articleSection\":[\"Allgemein\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.herzensraum-coaching.at\\\/warum-ich-es-liebe-coach-zu-sein\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.herzensraum-coaching.at\\\/warum-ich-es-liebe-coach-zu-sein\\\/\",\"url\":\"https:\\\/\\\/www.herzensraum-coaching.at\\\/warum-ich-es-liebe-coach-zu-sein\\\/\",\"name\":\"Warum ich es liebe, Coach zu sein! - Herzensraum-Coaching\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.herzensraum-coaching.at\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.herzensraum-coaching.at\\\/warum-ich-es-liebe-coach-zu-sein\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.herzensraum-coaching.at\\\/warum-ich-es-liebe-coach-zu-sein\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.herzensraum-coaching.at\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/sunrise-1157963_1280.jpg\",\"datePublished\":\"2019-04-18T14:15:28+00:00\",\"dateModified\":\"2019-04-18T14:15:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.herzensraum-coaching.at\\\/#\\\/schema\\\/person\\\/551800e2d7057ae8b86ec5c758987b6f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.herzensraum-coaching.at\\\/warum-ich-es-liebe-coach-zu-sein\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.herzensraum-coaching.at\\\/warum-ich-es-liebe-coach-zu-sein\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.herzensraum-coaching.at\\\/warum-ich-es-liebe-coach-zu-sein\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.herzensraum-coaching.at\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/sunrise-1157963_1280.jpg\",\"contentUrl\":\"https:\\\/\\\/www.herzensraum-coaching.at\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/sunrise-1157963_1280.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.herzensraum-coaching.at\\\/warum-ich-es-liebe-coach-zu-sein\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.herzensraum-coaching.at\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Warum ich es liebe, Coach zu sein!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.herzensraum-coaching.at\\\/#website\",\"url\":\"https:\\\/\\\/www.herzensraum-coaching.at\\\/\",\"name\":\"Herzensraum-Coaching\",\"description\":\"Mag. Nicole Riederer\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.herzensraum-coaching.at\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.herzensraum-coaching.at\\\/#\\\/schema\\\/person\\\/551800e2d7057ae8b86ec5c758987b6f\",\"name\":\"Nicole Riederer\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/33614f67f71415d7f18b204f828b0457f914da765934f165c2eb72e2545f6eb9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/33614f67f71415d7f18b204f828b0457f914da765934f165c2eb72e2545f6eb9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/33614f67f71415d7f18b204f828b0457f914da765934f165c2eb72e2545f6eb9?s=96&d=mm&r=g\",\"caption\":\"Nicole Riederer\"},\"sameAs\":[\"http:\\\/\\\/www.herzensraum-coaching.at\"],\"url\":\"https:\\\/\\\/www.herzensraum-coaching.at\\\/en\\\/author\\\/neekee\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Warum ich es liebe, Coach zu sein! - Herzensraum-Coaching","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.herzensraum-coaching.at\/en\/warum-ich-es-liebe-coach-zu-sein\/","og_locale":"en_US","og_type":"article","og_title":"Warum ich es liebe, Coach zu sein! - Herzensraum-Coaching","og_description":"Warum ich es liebe, Coach zu sein!","og_url":"https:\/\/www.herzensraum-coaching.at\/en\/warum-ich-es-liebe-coach-zu-sein\/","og_site_name":"Herzensraum-Coaching","article_publisher":"https:\/\/www.facebook.com\/herzensraum.coaching\/","article_published_time":"2019-04-18T14:15:28+00:00","article_modified_time":"2019-04-18T14:15:35+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.herzensraum-coaching.at\/wp-content\/uploads\/2019\/04\/sunrise-1157963_1280.jpg","type":"image\/jpeg"}],"author":"Nicole Riederer","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Nicole Riederer"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.herzensraum-coaching.at\/warum-ich-es-liebe-coach-zu-sein\/#article","isPartOf":{"@id":"https:\/\/www.herzensraum-coaching.at\/warum-ich-es-liebe-coach-zu-sein\/"},"author":{"name":"Nicole Riederer","@id":"https:\/\/www.herzensraum-coaching.at\/#\/schema\/person\/551800e2d7057ae8b86ec5c758987b6f"},"headline":"Warum ich es liebe, Coach zu sein!","datePublished":"2019-04-18T14:15:28+00:00","dateModified":"2019-04-18T14:15:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.herzensraum-coaching.at\/warum-ich-es-liebe-coach-zu-sein\/"},"wordCount":14,"commentCount":2,"image":{"@id":"https:\/\/www.herzensraum-coaching.at\/warum-ich-es-liebe-coach-zu-sein\/#primaryimage"},"thumbnailUrl":"https:\/\/www.herzensraum-coaching.at\/wp-content\/uploads\/2019\/04\/sunrise-1157963_1280.jpg","keywords":["Coach","Coaching","erfolgreich","Traumberuf"],"articleSection":["Allgemein"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.herzensraum-coaching.at\/warum-ich-es-liebe-coach-zu-sein\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.herzensraum-coaching.at\/warum-ich-es-liebe-coach-zu-sein\/","url":"https:\/\/www.herzensraum-coaching.at\/warum-ich-es-liebe-coach-zu-sein\/","name":"Warum ich es liebe, Coach zu sein! - Herzensraum-Coaching","isPartOf":{"@id":"https:\/\/www.herzensraum-coaching.at\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.herzensraum-coaching.at\/warum-ich-es-liebe-coach-zu-sein\/#primaryimage"},"image":{"@id":"https:\/\/www.herzensraum-coaching.at\/warum-ich-es-liebe-coach-zu-sein\/#primaryimage"},"thumbnailUrl":"https:\/\/www.herzensraum-coaching.at\/wp-content\/uploads\/2019\/04\/sunrise-1157963_1280.jpg","datePublished":"2019-04-18T14:15:28+00:00","dateModified":"2019-04-18T14:15:35+00:00","author":{"@id":"https:\/\/www.herzensraum-coaching.at\/#\/schema\/person\/551800e2d7057ae8b86ec5c758987b6f"},"breadcrumb":{"@id":"https:\/\/www.herzensraum-coaching.at\/warum-ich-es-liebe-coach-zu-sein\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.herzensraum-coaching.at\/warum-ich-es-liebe-coach-zu-sein\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.herzensraum-coaching.at\/warum-ich-es-liebe-coach-zu-sein\/#primaryimage","url":"https:\/\/www.herzensraum-coaching.at\/wp-content\/uploads\/2019\/04\/sunrise-1157963_1280.jpg","contentUrl":"https:\/\/www.herzensraum-coaching.at\/wp-content\/uploads\/2019\/04\/sunrise-1157963_1280.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.herzensraum-coaching.at\/warum-ich-es-liebe-coach-zu-sein\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.herzensraum-coaching.at\/"},{"@type":"ListItem","position":2,"name":"Warum ich es liebe, Coach zu sein!"}]},{"@type":"WebSite","@id":"https:\/\/www.herzensraum-coaching.at\/#website","url":"https:\/\/www.herzensraum-coaching.at\/","name":"Herzensraum-Coaching","description":"Mag. Nicole Riederer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.herzensraum-coaching.at\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.herzensraum-coaching.at\/#\/schema\/person\/551800e2d7057ae8b86ec5c758987b6f","name":"Nicole Riederer","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/33614f67f71415d7f18b204f828b0457f914da765934f165c2eb72e2545f6eb9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/33614f67f71415d7f18b204f828b0457f914da765934f165c2eb72e2545f6eb9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/33614f67f71415d7f18b204f828b0457f914da765934f165c2eb72e2545f6eb9?s=96&d=mm&r=g","caption":"Nicole Riederer"},"sameAs":["http:\/\/www.herzensraum-coaching.at"],"url":"https:\/\/www.herzensraum-coaching.at\/en\/author\/neekee\/"}]}},"jetpack_featured_media_url":"https:\/\/www.herzensraum-coaching.at\/wp-content\/uploads\/2019\/04\/sunrise-1157963_1280.jpg","jetpack_shortlink":"https:\/\/wp.me\/p7p2NK-bX","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.herzensraum-coaching.at\/en\/wp-json\/wp\/v2\/posts\/741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.herzensraum-coaching.at\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.herzensraum-coaching.at\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.herzensraum-coaching.at\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.herzensraum-coaching.at\/en\/wp-json\/wp\/v2\/comments?post=741"}],"version-history":[{"count":4,"href":"https:\/\/www.herzensraum-coaching.at\/en\/wp-json\/wp\/v2\/posts\/741\/revisions"}],"predecessor-version":[{"id":749,"href":"https:\/\/www.herzensraum-coaching.at\/en\/wp-json\/wp\/v2\/posts\/741\/revisions\/749"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.herzensraum-coaching.at\/en\/wp-json\/wp\/v2\/media\/747"}],"wp:attachment":[{"href":"https:\/\/www.herzensraum-coaching.at\/en\/wp-json\/wp\/v2\/media?parent=741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.herzensraum-coaching.at\/en\/wp-json\/wp\/v2\/categories?post=741"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.herzensraum-coaching.at\/en\/wp-json\/wp\/v2\/tags?post=741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}