{"id":551,"date":"2016-11-21T14:00:07","date_gmt":"2016-11-21T13:00:07","guid":{"rendered":"http:\/\/www.herzensraum-coaching.at\/?p=551"},"modified":"2020-02-19T22:44:03","modified_gmt":"2020-02-19T21:44:03","slug":"mein-spruch-des-monats-november","status":"publish","type":"post","link":"https:\/\/www.herzensraum-coaching.at\/en\/mein-spruch-des-monats-november\/","title":{"rendered":"Mein Spruch des Monats &#8211; November"},"content":{"rendered":"<h2 style=\"text-align: center;\">Mein Spruch des Monats November<\/h2>\n<p style=\"text-align: center;\">Jeder ist anders &#8211; darin sind wir gleich.<\/p>\n<p style=\"text-align: center;\">Wir alle teilen die Eigenschaft, dass jeder von uns einmalig&nbsp;ist auf dieser Welt &#8211;<br \/>\nund diese Individualit\u00e4t gilt es anzuerkennen, denn auf diese Weise kann ich mein Gegen\u00fcber sein lassen, wie es ist,<br \/>\ndarf mich an der Unterschiedlichkeit, die mich&nbsp;zugleich&nbsp;bereichert, freuen und kann so auch mich selbst in meiner Einzigartigkeit wahrnehmen.<\/p>\n<p style=\"text-align: center;\">Zu akzeptieren, dass jeder seine eigene Art zu sein und zu leben hat, w\u00fcrde meines Empfindens&nbsp;nach viel dazu beitragen,<br \/>\nin Harmonie und Symbiose miteinander zu leben &#8211; aus diesem Grund fand ich den Spruch von Jahn sehr ansprechend,<br \/>\ngerade in Zeiten wie diesen.<\/p>\n<p style=\"text-align: center;\">Ich freue mich \u00fcber Eure Meinung dazu \ud83d\ude42<\/p>\n<p style=\"text-align: center;\"><img fetchpriority=\"high\" decoding=\"async\" data-attachment-id=\"550\" data-permalink=\"https:\/\/www.herzensraum-coaching.at\/en\/herzensraum_frieden-480x640\/\" data-orig-file=\"https:\/\/www.herzensraum-coaching.at\/wp-content\/uploads\/2016\/11\/Herzensraum_Frieden-480x640.jpg\" data-orig-size=\"480,640\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;10&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon PowerShot SX210 IS&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1403087241&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;29.4&quot;,&quot;iso&quot;:&quot;80&quot;,&quot;shutter_speed&quot;:&quot;0.0008&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"herzensraum_frieden-480&amp;#215;640\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.herzensraum-coaching.at\/wp-content\/uploads\/2016\/11\/Herzensraum_Frieden-480x640.jpg\" class=\"wp-image-550 aligncenter\" src=\"http:\/\/www.herzensraum-coaching.at\/wp-content\/uploads\/2016\/11\/Herzensraum_Frieden-480x640-225x300.jpg\" alt=\"herzensraum_frieden-480x640\" width=\"350\" height=\"467\" srcset=\"https:\/\/www.herzensraum-coaching.at\/wp-content\/uploads\/2016\/11\/Herzensraum_Frieden-480x640-225x300.jpg 225w, https:\/\/www.herzensraum-coaching.at\/wp-content\/uploads\/2016\/11\/Herzensraum_Frieden-480x640.jpg 480w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/><\/p>\n<p style=\"text-align: center;\"><strong>PS:<\/strong> Das Foto stammt von der Fassade der Sagrada Familia in Barcelona,<br \/>\nsein Motiv hat mich sehr beeindruckt und passt f\u00fcr mich sehr gut zum Thema &lt;3<\/p>","protected":false},"excerpt":{"rendered":"<p>Mein Spruch des Monats November Jeder ist anders &#8211; darin sind wir gleich. Wir alle teilen die Eigenschaft, dass jeder von uns einmalig&nbsp;ist auf dieser Welt &#8211; und diese Individualit\u00e4t gilt es anzuerkennen, denn auf diese Weise kann ich mein Gegen\u00fcber sein lassen, wie es ist, darf mich an der Unterschiedlichkeit, die mich&nbsp;zugleich&nbsp;bereichert, freuen und [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[22],"tags":[],"class_list":["post-551","post","type-post","status-publish","format-standard","hentry","category-spruch-des-monats"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mein Spruch des Monats - November - Herzensraum-Coaching<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.herzensraum-coaching.at\/en\/mein-spruch-des-monats-november\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mein Spruch des Monats - November - Herzensraum-Coaching\" \/>\n<meta property=\"og:description\" content=\"Mein Spruch des Monats November Jeder ist anders &#8211; darin sind wir gleich. Wir alle teilen die Eigenschaft, dass jeder von uns einmalig&nbsp;ist auf dieser Welt &#8211; und diese Individualit\u00e4t gilt es anzuerkennen, denn auf diese Weise kann ich mein Gegen\u00fcber sein lassen, wie es ist, darf mich an der Unterschiedlichkeit, die mich&nbsp;zugleich&nbsp;bereichert, freuen und [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.herzensraum-coaching.at\/en\/mein-spruch-des-monats-november\/\" \/>\n<meta property=\"og:site_name\" content=\"Herzensraum-Coaching\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/herzensraum.coaching\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-21T13:00:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-19T21:44:03+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.herzensraum-coaching.at\/wp-content\/uploads\/2016\/11\/Herzensraum_Frieden-480x640-225x300.jpg\" \/>\n<meta name=\"author\" content=\"Nicole Riederer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nicole Riederer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.herzensraum-coaching.at\\\/mein-spruch-des-monats-november\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.herzensraum-coaching.at\\\/mein-spruch-des-monats-november\\\/\"},\"author\":{\"name\":\"Nicole Riederer\",\"@id\":\"https:\\\/\\\/www.herzensraum-coaching.at\\\/#\\\/schema\\\/person\\\/551800e2d7057ae8b86ec5c758987b6f\"},\"headline\":\"Mein Spruch des Monats &#8211; November\",\"datePublished\":\"2016-11-21T13:00:07+00:00\",\"dateModified\":\"2020-02-19T21:44:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.herzensraum-coaching.at\\\/mein-spruch-des-monats-november\\\/\"},\"wordCount\":159,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.herzensraum-coaching.at\\\/mein-spruch-des-monats-november\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.herzensraum-coaching.at\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/Herzensraum_Frieden-480x640-225x300.jpg\",\"articleSection\":[\"Spruch des Monats\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.herzensraum-coaching.at\\\/mein-spruch-des-monats-november\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.herzensraum-coaching.at\\\/mein-spruch-des-monats-november\\\/\",\"url\":\"https:\\\/\\\/www.herzensraum-coaching.at\\\/mein-spruch-des-monats-november\\\/\",\"name\":\"Mein Spruch des Monats - November - Herzensraum-Coaching\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.herzensraum-coaching.at\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.herzensraum-coaching.at\\\/mein-spruch-des-monats-november\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.herzensraum-coaching.at\\\/mein-spruch-des-monats-november\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.herzensraum-coaching.at\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/Herzensraum_Frieden-480x640-225x300.jpg\",\"datePublished\":\"2016-11-21T13:00:07+00:00\",\"dateModified\":\"2020-02-19T21:44:03+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.herzensraum-coaching.at\\\/#\\\/schema\\\/person\\\/551800e2d7057ae8b86ec5c758987b6f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.herzensraum-coaching.at\\\/mein-spruch-des-monats-november\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.herzensraum-coaching.at\\\/mein-spruch-des-monats-november\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.herzensraum-coaching.at\\\/mein-spruch-des-monats-november\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.herzensraum-coaching.at\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/Herzensraum_Frieden-480x640-225x300.jpg\",\"contentUrl\":\"http:\\\/\\\/www.herzensraum-coaching.at\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/Herzensraum_Frieden-480x640-225x300.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.herzensraum-coaching.at\\\/mein-spruch-des-monats-november\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.herzensraum-coaching.at\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mein Spruch des Monats &#8211; November\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.herzensraum-coaching.at\\\/#website\",\"url\":\"https:\\\/\\\/www.herzensraum-coaching.at\\\/\",\"name\":\"Herzensraum-Coaching\",\"description\":\"Mag. Nicole Riederer\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.herzensraum-coaching.at\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.herzensraum-coaching.at\\\/#\\\/schema\\\/person\\\/551800e2d7057ae8b86ec5c758987b6f\",\"name\":\"Nicole Riederer\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/33614f67f71415d7f18b204f828b0457f914da765934f165c2eb72e2545f6eb9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/33614f67f71415d7f18b204f828b0457f914da765934f165c2eb72e2545f6eb9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/33614f67f71415d7f18b204f828b0457f914da765934f165c2eb72e2545f6eb9?s=96&d=mm&r=g\",\"caption\":\"Nicole Riederer\"},\"sameAs\":[\"http:\\\/\\\/www.herzensraum-coaching.at\"],\"url\":\"https:\\\/\\\/www.herzensraum-coaching.at\\\/en\\\/author\\\/neekee\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mein Spruch des Monats - November - Herzensraum-Coaching","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.herzensraum-coaching.at\/en\/mein-spruch-des-monats-november\/","og_locale":"en_US","og_type":"article","og_title":"Mein Spruch des Monats - November - Herzensraum-Coaching","og_description":"Mein Spruch des Monats November Jeder ist anders &#8211; darin sind wir gleich. Wir alle teilen die Eigenschaft, dass jeder von uns einmalig&nbsp;ist auf dieser Welt &#8211; und diese Individualit\u00e4t gilt es anzuerkennen, denn auf diese Weise kann ich mein Gegen\u00fcber sein lassen, wie es ist, darf mich an der Unterschiedlichkeit, die mich&nbsp;zugleich&nbsp;bereichert, freuen und [&hellip;]","og_url":"https:\/\/www.herzensraum-coaching.at\/en\/mein-spruch-des-monats-november\/","og_site_name":"Herzensraum-Coaching","article_publisher":"https:\/\/www.facebook.com\/herzensraum.coaching\/","article_published_time":"2016-11-21T13:00:07+00:00","article_modified_time":"2020-02-19T21:44:03+00:00","og_image":[{"url":"http:\/\/www.herzensraum-coaching.at\/wp-content\/uploads\/2016\/11\/Herzensraum_Frieden-480x640-225x300.jpg","type":"","width":"","height":""}],"author":"Nicole Riederer","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Nicole Riederer","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.herzensraum-coaching.at\/mein-spruch-des-monats-november\/#article","isPartOf":{"@id":"https:\/\/www.herzensraum-coaching.at\/mein-spruch-des-monats-november\/"},"author":{"name":"Nicole Riederer","@id":"https:\/\/www.herzensraum-coaching.at\/#\/schema\/person\/551800e2d7057ae8b86ec5c758987b6f"},"headline":"Mein Spruch des Monats &#8211; November","datePublished":"2016-11-21T13:00:07+00:00","dateModified":"2020-02-19T21:44:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.herzensraum-coaching.at\/mein-spruch-des-monats-november\/"},"wordCount":159,"commentCount":0,"image":{"@id":"https:\/\/www.herzensraum-coaching.at\/mein-spruch-des-monats-november\/#primaryimage"},"thumbnailUrl":"http:\/\/www.herzensraum-coaching.at\/wp-content\/uploads\/2016\/11\/Herzensraum_Frieden-480x640-225x300.jpg","articleSection":["Spruch des Monats"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.herzensraum-coaching.at\/mein-spruch-des-monats-november\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.herzensraum-coaching.at\/mein-spruch-des-monats-november\/","url":"https:\/\/www.herzensraum-coaching.at\/mein-spruch-des-monats-november\/","name":"Mein Spruch des Monats - November - Herzensraum-Coaching","isPartOf":{"@id":"https:\/\/www.herzensraum-coaching.at\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.herzensraum-coaching.at\/mein-spruch-des-monats-november\/#primaryimage"},"image":{"@id":"https:\/\/www.herzensraum-coaching.at\/mein-spruch-des-monats-november\/#primaryimage"},"thumbnailUrl":"http:\/\/www.herzensraum-coaching.at\/wp-content\/uploads\/2016\/11\/Herzensraum_Frieden-480x640-225x300.jpg","datePublished":"2016-11-21T13:00:07+00:00","dateModified":"2020-02-19T21:44:03+00:00","author":{"@id":"https:\/\/www.herzensraum-coaching.at\/#\/schema\/person\/551800e2d7057ae8b86ec5c758987b6f"},"breadcrumb":{"@id":"https:\/\/www.herzensraum-coaching.at\/mein-spruch-des-monats-november\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.herzensraum-coaching.at\/mein-spruch-des-monats-november\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.herzensraum-coaching.at\/mein-spruch-des-monats-november\/#primaryimage","url":"http:\/\/www.herzensraum-coaching.at\/wp-content\/uploads\/2016\/11\/Herzensraum_Frieden-480x640-225x300.jpg","contentUrl":"http:\/\/www.herzensraum-coaching.at\/wp-content\/uploads\/2016\/11\/Herzensraum_Frieden-480x640-225x300.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.herzensraum-coaching.at\/mein-spruch-des-monats-november\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.herzensraum-coaching.at\/"},{"@type":"ListItem","position":2,"name":"Mein Spruch des Monats &#8211; November"}]},{"@type":"WebSite","@id":"https:\/\/www.herzensraum-coaching.at\/#website","url":"https:\/\/www.herzensraum-coaching.at\/","name":"Herzensraum-Coaching","description":"Mag. Nicole Riederer","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.herzensraum-coaching.at\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.herzensraum-coaching.at\/#\/schema\/person\/551800e2d7057ae8b86ec5c758987b6f","name":"Nicole Riederer","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/33614f67f71415d7f18b204f828b0457f914da765934f165c2eb72e2545f6eb9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/33614f67f71415d7f18b204f828b0457f914da765934f165c2eb72e2545f6eb9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/33614f67f71415d7f18b204f828b0457f914da765934f165c2eb72e2545f6eb9?s=96&d=mm&r=g","caption":"Nicole Riederer"},"sameAs":["http:\/\/www.herzensraum-coaching.at"],"url":"https:\/\/www.herzensraum-coaching.at\/en\/author\/neekee\/"}]}},"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p7p2NK-8T","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.herzensraum-coaching.at\/en\/wp-json\/wp\/v2\/posts\/551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.herzensraum-coaching.at\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.herzensraum-coaching.at\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.herzensraum-coaching.at\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.herzensraum-coaching.at\/en\/wp-json\/wp\/v2\/comments?post=551"}],"version-history":[{"count":6,"href":"https:\/\/www.herzensraum-coaching.at\/en\/wp-json\/wp\/v2\/posts\/551\/revisions"}],"predecessor-version":[{"id":1031,"href":"https:\/\/www.herzensraum-coaching.at\/en\/wp-json\/wp\/v2\/posts\/551\/revisions\/1031"}],"wp:attachment":[{"href":"https:\/\/www.herzensraum-coaching.at\/en\/wp-json\/wp\/v2\/media?parent=551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.herzensraum-coaching.at\/en\/wp-json\/wp\/v2\/categories?post=551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.herzensraum-coaching.at\/en\/wp-json\/wp\/v2\/tags?post=551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}